{"id":1087,"count":1,"description":"","link":"https:\/\/www.indir.com\/haber\/etiket\/google-play-hizmetleri\/","name":"Google Play Hizmetleri","slug":"google-play-hizmetleri","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.indir.com\/haber\/wp-json\/wp\/v2\/tags\/1087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.indir.com\/haber\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.indir.com\/haber\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.indir.com\/haber\/wp-json\/wp\/v2\/posts?tags=1087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}