{"id":46879,"date":"2023-04-27T11:30:00","date_gmt":"2023-04-27T08:30:00","guid":{"rendered":"https:\/\/www.indir.com\/haber\/?p=46879"},"modified":"2023-04-28T11:17:08","modified_gmt":"2023-04-28T08:17:08","slug":"xiaomiden-guncelleme-destegini-kaybeden-bir-cihaz-daha","status":"publish","type":"post","link":"https:\/\/www.indir.com\/haber\/xiaomiden-guncelleme-destegini-kaybeden-bir-cihaz-daha\/","title":{"rendered":"Xiaomi\u2019den g\u00fcncelleme deste\u011fini kaybeden bir cihaz daha"},"content":{"rendered":"\n<p>Ak\u0131ll\u0131 telefon sekt\u00f6r\u00fcnde yaz\u0131l\u0131m g\u00fcncellemeleri, cihazlar\u0131n \u00f6mr\u00fcn\u00fc uzatmak i\u00e7in olduk\u00e7a \u00f6nemli bir konu. Xiaomi gibi bir\u00e7ok \u00fcretici, cihazlar\u0131n g\u00fcncelleme deste\u011fi s\u00fcresini belirliyor ve bu s\u00fcre dolunca yaz\u0131l\u0131m g\u00fcncellemelerini sonland\u0131r\u0131yor. Xiaomi, EOS listesi ad\u0131 verilen ve g\u00fcncelleme deste\u011fi biten modellerin yer ald\u0131\u011f\u0131 bir liste ile kullan\u0131c\u0131lar\u0131 bilgilendiriyor.<\/p>\n\n\n\n<p>EOS listesine eklenen cihazlar, MIUI, Android veya g\u00fcvenlik g\u00fcncellemelerini alamayacaklar. Ancak, Xiaomi \u015firketi, \u00f6nemli bir g\u00fcvenlik a\u00e7\u0131\u011f\u0131 tespit edildi\u011fi takdirde, cihazlar g\u00fcncelleme deste\u011finden \u00e7\u0131ksa bile g\u00fcncelleme almaya devam edeceklerini belirtiyor.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Xiaomi, EOS Listesindeki G\u00fcncelleme Deste\u011fi Biten Cihazlar Listesine Mi 10 Lite Zoom Modelini Ekledi<\/h2>\n\n\n\n<p>Xiaomi, son g\u00fcncelleme ile Mi 10 Lite Zoom modelinin g\u00fcncelleme deste\u011fini sonland\u0131rd\u0131\u011f\u0131n\u0131 duyurdu. Sekt\u00f6rde bir\u00e7ok \u00fcretici gibi Xiaomi de donan\u0131msal a\u00e7\u0131dan yeni s\u00fcr\u00fcmleri \u00e7al\u0131\u015ft\u0131ramayan ve art\u0131k milad\u0131n\u0131 doldurmu\u015f cihazlar i\u00e7in yaz\u0131l\u0131m deste\u011fini kesiyor.<\/p>\n\n\n\n<p>Mi 10 Lite Zoom modeli, iki y\u0131ll\u0131k yaz\u0131l\u0131m deste\u011fi s\u00fcresinin dolmas\u0131 nedeniyle g\u00fcncelleme deste\u011finden \u00e7\u0131kar\u0131ld\u0131. Xiaomi&#8217;nin EOS listesi, g\u00fcncelleme deste\u011fi biten cihazlar\u0131n takip edilmesi i\u00e7in kullan\u0131c\u0131lara \u00f6nemli bir kaynak olu\u015fturuyor. Bu sayede, kullan\u0131c\u0131lar hangi cihazlar\u0131n g\u00fcncelleme deste\u011finden \u00e7\u0131kt\u0131\u011f\u0131n\u0131 \u00f6\u011frenerek, daha bilin\u00e7li bir tercih yapabiliyorlar.<\/p>\n\n\n\n<p><strong>G\u00fcncelleme deste\u011fi sona eren di\u011fer t\u00fcm Xiaomi modelleri a\u015fa\u011f\u0131daki yer al\u0131yor:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>&nbsp;Mi 1<\/li>\n\n\n\n<li>Mi 2<\/li>\n\n\n\n<li>Mi 2A<\/li>\n\n\n\n<li>Mi 3<\/li>\n\n\n\n<li>Mi 4<\/li>\n\n\n\n<li>Mi 4S<\/li>\n\n\n\n<li>Mi 4C<\/li>\n\n\n\n<li>Mi 5<\/li>\n\n\n\n<li>Mi 5S<\/li>\n\n\n\n<li>Mi 5S Plus<\/li>\n\n\n\n<li>Mi 5C<\/li>\n\n\n\n<li>Mi 5X<\/li>\n\n\n\n<li>Mi 6<\/li>\n\n\n\n<li>Mi 6X<\/li>\n\n\n\n<li>Mi 8<\/li>\n\n\n\n<li>Mi 8 Lite<\/li>\n\n\n\n<li>Mi 8 SE<\/li>\n\n\n\n<li>Mi 8 UD<\/li>\n\n\n\n<li>Mi 8 Pro<\/li>\n\n\n\n<li>Mi 8 Explore Edition<\/li>\n\n\n\n<li>Mi 9<\/li>\n\n\n\n<li>Mi 9 Lite<\/li>\n\n\n\n<li>Mi 9 Pro 5G<\/li>\n\n\n\n<li>Mi 9T Pro<\/li>\n\n\n\n<li>Mi 9 SE<\/li>\n\n\n\n<li>Mi CC 9<\/li>\n\n\n\n<li>Mi CC 9e<\/li>\n\n\n\n<li>Mi CC 9 Pro<\/li>\n\n\n\n<li>Mi Note<\/li>\n\n\n\n<li>Mi Note 2<\/li>\n\n\n\n<li>Mi Note 3<\/li>\n\n\n\n<li>Mi Note Pro<\/li>\n\n\n\n<li>MIX<\/li>\n\n\n\n<li>MIX 2<\/li>\n\n\n\n<li>Mi MAX<\/li>\n\n\n\n<li>Mi MAX 2<\/li>\n\n\n\n<li>Mi MAX 3<\/li>\n\n\n\n<li>Mi A1<\/li>\n\n\n\n<li>Mi A2<\/li>\n\n\n\n<li>Mi A2 Lite<\/li>\n\n\n\n<li>Mi A3 (Android One)<\/li>\n\n\n\n<li>Mi Pad<\/li>\n\n\n\n<li>Mi Pad 2<\/li>\n\n\n\n<li>Mi Pad 3<\/li>\n\n\n\n<li>Mi Pad 4<\/li>\n\n\n\n<li>Mi Pad 4 Plus<\/li>\n\n\n\n<li>MIX 2S<\/li>\n\n\n\n<li>Mi MIX 2S<\/li>\n\n\n\n<li>MIX 3<\/li>\n\n\n\n<li>Mi MIX 3<\/li>\n\n\n\n<li>Mi PLAY<\/li>\n\n\n\n<li>Mi Note 10<\/li>\n\n\n\n<li>Mi 10 Lite Zoom<\/li>\n\n\n\n<li>Redmi 1<\/li>\n\n\n\n<li>Redmi 1S<\/li>\n\n\n\n<li>Redmi 2<\/li>\n\n\n\n<li>Redmi 2A<\/li>\n\n\n\n<li>Redmi 3<\/li>\n\n\n\n<li>Redmi 3S<\/li>\n\n\n\n<li>Redmi 3X<\/li>\n\n\n\n<li>Redmi 4<\/li>\n\n\n\n<li>Redmi 4X<\/li>\n\n\n\n<li>Redmi 4A<\/li>\n\n\n\n<li>Redmi 5<\/li>\n\n\n\n<li>Redmi 5 Plus<\/li>\n\n\n\n<li>Redmi 5A<\/li>\n\n\n\n<li>Redmi Note 1<\/li>\n\n\n\n<li>Redmi Note 1S<\/li>\n\n\n\n<li>Redmi Note 2<\/li>\n\n\n\n<li>Redmi Note 2 Pro<\/li>\n\n\n\n<li>Redmi Note 3<\/li>\n\n\n\n<li>Redmi Note 4<\/li>\n\n\n\n<li>Redmi Note 4X<\/li>\n\n\n\n<li>Redmi Note 5<\/li>\n\n\n\n<li>Redmi Note 5A<\/li>\n\n\n\n<li>Redmi Note 5 Pro<\/li>\n\n\n\n<li>Redmi Pro<\/li>\n\n\n\n<li>Redmi 6<\/li>\n\n\n\n<li>Redmi 6 Pro<\/li>\n\n\n\n<li>Redmi 6A<\/li>\n\n\n\n<li>Redmi Note 6 Pro<\/li>\n\n\n\n<li>Redmi S2<\/li>\n\n\n\n<li>Redmi Y2<\/li>\n\n\n\n<li>Redmi Go<\/li>\n\n\n\n<li>Redmi Note 7<\/li>\n\n\n\n<li>Redmi Note 7S<\/li>\n\n\n\n<li>Redmi Note 7 Pro<\/li>\n\n\n\n<li>Redmi K20<\/li>\n\n\n\n<li>Redmi 7<\/li>\n\n\n\n<li>Redmi Y3<\/li>\n\n\n\n<li>Redmi K20 Pro<\/li>\n\n\n\n<li>Redmi 7A<\/li>\n\n\n\n<li>Redmi 8<\/li>\n\n\n\n<li>Redmi Note 8 Pro<\/li>\n\n\n\n<li>Redmi Note 8T<\/li>\n\n\n\n<li>Redmi 8A<\/li>\n\n\n\n<li>Redmi Note 8 (ID)<\/li>\n\n\n\n<li>Redmi 8A Dual<\/li>\n\n\n\n<li>Redmi Note 8 (IN)<\/li>\n\n\n\n<li>Redmi Note 8 (GLOBAL)<\/li>\n\n\n\n<li>Redmi Note 8 (CN)<\/li>\n\n\n\n<li>Redmi K30<\/li>\n\n\n\n<li>Redmi K30 5G<\/li>\n\n\n\n<li>Redmi K30 5G Speed<\/li>\n\n\n\n<li>POCO F1<\/li>\n\n\n\n<li>POCO PHONE F1<\/li>\n\n\n\n<li>POCO X2<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Ak\u0131ll\u0131 telefon sekt\u00f6r\u00fcnde yaz\u0131l\u0131m g\u00fcncellemeleri, cihazlar\u0131n \u00f6mr\u00fcn\u00fc uzatmak i\u00e7in olduk\u00e7a \u00f6nemli bir konu. Xiaomi gibi bir\u00e7ok \u00fcretici, cihazlar\u0131n g\u00fcncelleme deste\u011fi s\u00fcresini belirliyor ve bu s\u00fcre dolunca yaz\u0131l\u0131m g\u00fcncellemelerini sonland\u0131r\u0131yor. Xiaomi, EOS listesi ad\u0131 verilen ve g\u00fcncelleme deste\u011fi biten modellerin yer ald\u0131\u011f\u0131 bir liste ile kullan\u0131c\u0131lar\u0131 bilgilendiriyor. EOS listesine eklenen cihazlar, MIUI, Android veya g\u00fcvenlik g\u00fcncellemelerini [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":35854,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[80,1872,63,112],"class_list":["post-46879","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-yazilim","tag-android","tag-guncelleme","tag-iphone","tag-xiaomi"],"_links":{"self":[{"href":"https:\/\/www.indir.com\/haber\/wp-json\/wp\/v2\/posts\/46879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.indir.com\/haber\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.indir.com\/haber\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.indir.com\/haber\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/www.indir.com\/haber\/wp-json\/wp\/v2\/comments?post=46879"}],"version-history":[{"count":0,"href":"https:\/\/www.indir.com\/haber\/wp-json\/wp\/v2\/posts\/46879\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.indir.com\/haber\/wp-json\/wp\/v2\/media\/35854"}],"wp:attachment":[{"href":"https:\/\/www.indir.com\/haber\/wp-json\/wp\/v2\/media?parent=46879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.indir.com\/haber\/wp-json\/wp\/v2\/categories?post=46879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.indir.com\/haber\/wp-json\/wp\/v2\/tags?post=46879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}